{"id":40312,"date":"2017-07-15T19:00:59","date_gmt":"2017-07-15T18:00:59","guid":{"rendered":"http:\/\/www.lobosonda.com\/?p=40312\/"},"modified":"2017-07-07T15:55:47","modified_gmt":"2017-07-07T14:55:47","slug":"29-06-2017-fressen-fressen-fressen","status":"publish","type":"post","link":"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/","title":{"rendered":"29.06.2017 \u2013 Fressen, fressen, fressen"},"content":{"rendered":"<p style=\"text-align: justify;\">W\u00e4hrend unseres Tages auf dem Meer gab es heute hier und da verschiedene Fresssituationen. Gut, f\u00fcr die Atlantischen Fleckendelfine (nur am Morgen) und auch die Gro\u00dfen T\u00fcmmler, die die Chance hatten, ihre B\u00e4uche zu f\u00fcllen. Am Tag legen Delfine durchschnittlich Strecken um die hundert Kilometer zur\u00fcck, um ihre Nahrung zu finden. Das ist eine ziemliche Leistung, nicht zu vergessen, dass sie ihre Beute dann noch erjagen m\u00fcssen. Dies bedeutet ein Energieverlust f\u00fcr die Energieaufnahme. In solchen Situation ist es manchmal besser die Tiere fr\u00fcher zu verlassen, damit die Tiere Zeit haben, ihrer Lieblingsbesch\u00e4ftigung nachzukommen. Am Nachmittag gab es ein Gr\u00fcppchen von Gemeinen Delfinen, die unser Boot dann ein Weilchen begleiteten.<\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: 10pt;\">von Fatima Kutzschbach<\/span><\/p>\n<p><u><em><strong>Sichtungen des Tages<\/strong><\/em>:<\/u><\/p>\n<p>Ribeira Brava<\/p>\n<p><strong>09.00<\/strong>:\u00a0Atlantische Fleckendelfine, Gro\u00dfe T\u00fcmmler<\/p>\n<p><strong>13.30<\/strong>: Gro\u00dfe T\u00fcmmler, Gemeine Delfine<\/p>\n<p>&nbsp;<\/p>\n<p>Stenella<\/p>\n<p><strong>09.00<\/strong>: Atlantische Fleckendelfine<\/p>\n<p>&nbsp;<\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#sc_gallery-5918 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#sc_gallery-5918 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 33.33%;\n\t\t\t\t}\n\t\t\t\t#sc_gallery-5918 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#sc_gallery-5918 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see sc_gallery() in functions\/theme-shortcodes.php *\/\n\t\t\t<\/style>\n\t\t<div id='sc_gallery-5918' class='gallery element_classes galleryid-40312 gallery-columns-3 gallery-size-thumbnail '><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/29-06-2017-fressen-fressen-fressen\/dsc_4806-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4806-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4806-1-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4806-1-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4806-1-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4806-1-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/29-06-2017-fressen-fressen-fressen\/dsc_4810-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4810-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4810-1-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4810-1-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4810-1-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4810-1-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/29-06-2017-fressen-fressen-fressen\/dsc_4848-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4848-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4848-1-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4848-1-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4848-1-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4848-1-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/29-06-2017-fressen-fressen-fressen\/dsc_4870-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4870-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4870-1-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4870-1-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4870-1-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4870-1-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/29-06-2017-fressen-fressen-fressen\/dsc_4890-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4890-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4890-1-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4890-1-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4890-1-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4890-1-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/29-06-2017-fressen-fressen-fressen\/dsc_4897-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4897-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4897-1-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4897-1-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4897-1-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4897-1-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/29-06-2017-fressen-fressen-fressen\/dsc_4911-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4911-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4911-1-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4911-1-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4911-1-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4911-1-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/29-06-2017-fressen-fressen-fressen\/dsc_4937-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4937-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4937-1-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4937-1-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4937-1-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4937-1-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/29-06-2017-fressen-fressen-fressen\/dsc_4939-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4939-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4939-1-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4939-1-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4939-1-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_4939-1-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/29-06-2017-fressen-fressen-fressen\/dsc_9698-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9698-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9698-2-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9698-2-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9698-2-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9698-2-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/29-06-2017-fressen-fressen-fressen\/dsc_9761-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9761-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9761-2-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9761-2-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9761-2-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9761-2-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/29-06-2017-fressen-fressen-fressen\/dsc_9768-5\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9768-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9768-2-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9768-2-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9768-2-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9768-2-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/29-06-2017-fressen-fressen-fressen\/dsc_9777-5\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9777-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9777-2-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9777-2-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9777-2-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9777-2-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/29-06-2017-fressen-fressen-fressen\/dsc_9808-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9808-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9808-2-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9808-2-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9808-2-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9808-2-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl>\n\t\t\t\t<br style='clear: both' \/>\n\t\t\t<\/div>\n\n<p><span style=\"border-top-left-radius: 2px; border-top-right-radius: 2px; border-bottom-right-radius: 2px; border-bottom-left-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font-style: normal; font-variant-caps: normal; font-weight: bold; font-size: 11px; line-height: 20px; font-family: 'Helvetica Neue', Helvetica, sans-serif; color: #ffffff; background-image: url(data:image\/svg+xml; base64,phn2zyb4bwxucz0iahr0cdovl3d3dy53my5vcmcvmjawmc9zdmciighlawdodd0imzbwecigd2lkdgg9ijmwchgiihzpzxdcb3g9ii0xic0xidmxidmxij48zz48cgf0acbkpsjnmjkundq5lde0ljy2mibdmjkundq5ldiyljcymiaymi44njgsmjkumju2ide0ljc1ldi5lji1nibdni42mzismjkumju2idaumduxldiyljcymiawlja1mswxnc42njigqzaumduxldyunjaxidyunjmyldaumdy3ide0ljc1ldaumdy3iemymi44njgsmc4wnjcgmjkundq5ldyunjaxidi5ljq0oswxnc42njiiigzpbgw9iinmzmyiihn0cm9rzt0ii2zmziigc3ryb2tllxdpzhropsixij48l3bhdgg+phbhdgggzd0itte0ljczmywxljy4nibdny41mtysms42odygms42njusny40otugms42njusmtqunjyyiemxljy2nswymc4xntkgns4xmdksmjquodu0idkuotcsmjyunzq0iem5ljg1niwyns43mtggos43ntmsmjqumtqzidewljaxniwymy4wmjigqzewlji1mywymi4wmsaxms41ndgsmtyuntcyidexlju0ocwxni41nzigqzexlju0ocwxni41nzigmteumtu3lde1ljc5nsaxms4xntcsmtqunjq2iemxms4xntcsmtiuodqyideyljixmswxms40otugmtmuntiyldexljq5nsbdmtqunjm3ldexljq5nsaxns4xnzusmtiumzi2ide1lje3nswxmy4zmjmgqze1lje3nswxnc40mzygmtqundyylde2ljegmtqumdkzlde3ljy0mybdmtmunzg1lde4ljkznsaxnc43ndusmtkuotg4ide2ljayocwxos45odggqze4ljm1mswxos45odggmjaumtm2lde3lju1niaymc4xmzysmtqumdq2iemymc4xmzysmtauotm5ide3ljg4ocw4ljc2nyaxnc42nzgsoc43njcgqzewljk1osw4ljc2nya4ljc3nywxms41mzygoc43nzcsmtqumzk4iem4ljc3nywxns41mtmgos4ymswxni43mdkgos43ndksmtcumzu5iem5ljg1niwxny40odggos44nzismtcunia5ljg0lde3ljczmsbdos43ndesmtgumtqxidkuntismtkumdizidkundc3lde5ljiwmybdos40miwxos40nca5lji4ocwxos40otegos4wncwxos4znzygqzcunda4lde4ljyymia2ljm4nywxni4yntigni4zodcsmtqumzq5iem2ljm4nywxmc4yntygos4zodmsni40otcgmtuumdiyldyundk3iemxos41ntusni40otcgmjmumdc4ldkunza1idizlja3ocwxmy45otegqzizlja3ocwxoc40njmgmjaumjm5ldiylja2miaxni4yotcsmjiumdyyiemxnc45nzmsmjiumdyyidezljcyocwyms4znzkgmtmumzayldiwlju3mibdmtmumzayldiwlju3miaxmi42ndcsmjmumdugmtiundg4ldizljy1nybdmtiumtkzldi0ljc4ncaxms4zotysmjyumtk2idewljg2mywyny4wntggqzeylja4niwyny40mzqgmtmumzg2ldi3ljyznyaxnc43mzmsmjcunjm3iemyms45nswyny42mzcgmjcuodaxldixljgyocayny44mdesmtqunjyyiemyny44mdesny40otugmjeuotusms42odygmtqunzmzldeunjg2iibmawxspsijymqwodfjij48l3bhdgg+pc9npjwvc3znpg==); background-size: 14px 14px; background-color: #bd081c; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer; border: none; -webkit-font-smoothing: antialiased; background-position: 3px 50%; background-repeat: no-repeat no-repeat;\">Save<\/span><span style=\"border-top-left-radius: 2px; border-top-right-radius: 2px; border-bottom-right-radius: 2px; border-bottom-left-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font-style: normal; font-variant-caps: normal; font-weight: bold; font-size: 11px; line-height: 20px; font-family: 'Helvetica Neue', Helvetica, sans-serif; color: #ffffff; background-image: url(data:image\/svg+xml; base64,phn2zyb4bwxucz0iahr0cdovl3d3dy53my5vcmcvmjawmc9zdmciighlawdodd0imzbwecigd2lkdgg9ijmwchgiihzpzxdcb3g9ii0xic0xidmxidmxij48zz48cgf0acbkpsjnmjkundq5lde0ljy2mibdmjkundq5ldiyljcymiaymi44njgsmjkumju2ide0ljc1ldi5lji1nibdni42mzismjkumju2idaumduxldiyljcymiawlja1mswxnc42njigqzaumduxldyunjaxidyunjmyldaumdy3ide0ljc1ldaumdy3iemymi44njgsmc4wnjcgmjkundq5ldyunjaxidi5ljq0oswxnc42njiiigzpbgw9iinmzmyiihn0cm9rzt0ii2zmziigc3ryb2tllxdpzhropsixij48l3bhdgg+phbhdgggzd0itte0ljczmywxljy4nibdny41mtysms42odygms42njusny40otugms42njusmtqunjyyiemxljy2nswymc4xntkgns4xmdksmjquodu0idkuotcsmjyunzq0iem5ljg1niwyns43mtggos43ntmsmjqumtqzidewljaxniwymy4wmjigqzewlji1mywymi4wmsaxms41ndgsmtyuntcyidexlju0ocwxni41nzigqzexlju0ocwxni41nzigmteumtu3lde1ljc5nsaxms4xntcsmtqunjq2iemxms4xntcsmtiuodqyideyljixmswxms40otugmtmuntiyldexljq5nsbdmtqunjm3ldexljq5nsaxns4xnzusmtiumzi2ide1lje3nswxmy4zmjmgqze1lje3nswxnc40mzygmtqundyylde2ljegmtqumdkzlde3ljy0mybdmtmunzg1lde4ljkznsaxnc43ndusmtkuotg4ide2ljayocwxos45odggqze4ljm1mswxos45odggmjaumtm2lde3lju1niaymc4xmzysmtqumdq2iemymc4xmzysmtauotm5ide3ljg4ocw4ljc2nyaxnc42nzgsoc43njcgqzewljk1osw4ljc2nya4ljc3nywxms41mzygoc43nzcsmtqumzk4iem4ljc3nywxns41mtmgos4ymswxni43mdkgos43ndksmtcumzu5iem5ljg1niwxny40odggos44nzismtcunia5ljg0lde3ljczmsbdos43ndesmtgumtqxidkuntismtkumdizidkundc3lde5ljiwmybdos40miwxos40nca5lji4ocwxos40otegos4wncwxos4znzygqzcunda4lde4ljyymia2ljm4nywxni4yntigni4zodcsmtqumzq5iem2ljm4nywxmc4yntygos4zodmsni40otcgmtuumdiyldyundk3iemxos41ntusni40otcgmjmumdc4ldkunza1idizlja3ocwxmy45otegqzizlja3ocwxoc40njmgmjaumjm5ldiylja2miaxni4yotcsmjiumdyyiemxnc45nzmsmjiumdyyidezljcyocwyms4znzkgmtmumzayldiwlju3mibdmtmumzayldiwlju3miaxmi42ndcsmjmumdugmtiundg4ldizljy1nybdmtiumtkzldi0ljc4ncaxms4zotysmjyumtk2idewljg2mywyny4wntggqzeylja4niwyny40mzqgmtmumzg2ldi3ljyznyaxnc43mzmsmjcunjm3iemyms45nswyny42mzcgmjcuodaxldixljgyocayny44mdesmtqunjyyiemyny44mdesny40otugmjeuotusms42odygmtqunzmzldeunjg2iibmawxspsijymqwodfjij48l3bhdgg+pc9npjwvc3znpg==); background-size: 14px 14px; background-color: #bd081c; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer; border: none; -webkit-font-smoothing: antialiased; background-position: 3px 50%; background-repeat: no-repeat no-repeat;\">Save<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>W\u00e4hrend unseres Tages auf dem Meer gab es heute hier und da verschiedene Fresssituationen. Gut, f\u00fcr die Atlantischen Fleckendelfine (nur am Morgen) und auch die Gro\u00dfen<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":4,"featured_media":40309,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"29.06.2017 \u2013 Fressen, fressen, fressen","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2},"_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[1837,1846,1844,1842],"tags":[],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>29.06.2017 \u2013 Fressen, fressen, fressen - Lobosonda | Whalewatching | Madeira<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"29.06.2017 \u2013 Fressen, fressen, fressen - Lobosonda | Whalewatching | Madeira\" \/>\n<meta property=\"og:description\" content=\"W\u00e4hrend unseres Tages auf dem Meer gab es heute hier und da verschiedene Fresssituationen. Gut, f\u00fcr die Atlantischen Fleckendelfine (nur am Morgen) und auch die Gro\u00dfen [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/\" \/>\n<meta property=\"og:site_name\" content=\"Lobosonda | Whalewatching | Madeira\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lobosonda\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-15T18:00:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-07-07T14:55:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9808-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4252\" \/>\n\t<meta property=\"og:image:height\" content=\"2835\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"lobosonda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"lobosonda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/\"},\"author\":{\"name\":\"lobosonda\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#\/schema\/person\/16135f75aca699492fd26a7141197b03\"},\"headline\":\"29.06.2017 \u2013 Fressen, fressen, fressen\",\"datePublished\":\"2017-07-15T18:00:59+00:00\",\"dateModified\":\"2017-07-07T14:55:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/\"},\"wordCount\":156,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9808-2.jpg\",\"articleSection\":[\"Delfine\",\"Fleckendelfin\",\"Gemeiner Delfin\",\"Gro\u00dfer T\u00fcmmler\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/\",\"url\":\"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/\",\"name\":\"29.06.2017 \u2013 Fressen, fressen, fressen - Lobosonda | Whalewatching | Madeira\",\"isPartOf\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9808-2.jpg\",\"datePublished\":\"2017-07-15T18:00:59+00:00\",\"dateModified\":\"2017-07-07T14:55:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/#primaryimage\",\"url\":\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9808-2.jpg\",\"contentUrl\":\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9808-2.jpg\",\"width\":4252,\"height\":2835},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.lobosonda.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"29.06.2017 \u2013 Fressen, fressen, fressen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#website\",\"url\":\"https:\/\/blog.lobosonda.com\/de\/\",\"name\":\"Lobosonda | Whalewatching | Madeira\",\"description\":\"We stand for Water, Whales, Whale Watching, Whale conservation, Wellness and for Welcome. Lobosonda is a whale watching company respectful of all marine biodiversity operating in Madeira since 2003.\",\"publisher\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.lobosonda.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#organization\",\"name\":\"LobosOnda.com\",\"url\":\"https:\/\/blog.lobosonda.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lobosonda.com\/wp-content\/uploads\/2015\/04\/26167722_1853708551347437_4239983716863157418_n.jpg\",\"contentUrl\":\"https:\/\/www.lobosonda.com\/wp-content\/uploads\/2015\/04\/26167722_1853708551347437_4239983716863157418_n.jpg\",\"width\":480,\"height\":480,\"caption\":\"LobosOnda.com\"},\"image\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/lobosonda\/\",\"https:\/\/instagram.com\/lobosonda\/\",\"https:\/\/www.youtube.com\/user\/lobosonda\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#\/schema\/person\/16135f75aca699492fd26a7141197b03\",\"name\":\"lobosonda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f333a6edc75221163a5147e29206c9fe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f333a6edc75221163a5147e29206c9fe?s=96&d=mm&r=g\",\"caption\":\"lobosonda\"},\"url\":\"https:\/\/blog.lobosonda.com\/de\/author\/lobosonda\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"29.06.2017 \u2013 Fressen, fressen, fressen - Lobosonda | Whalewatching | Madeira","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/","og_locale":"de_DE","og_type":"article","og_title":"29.06.2017 \u2013 Fressen, fressen, fressen - Lobosonda | Whalewatching | Madeira","og_description":"W\u00e4hrend unseres Tages auf dem Meer gab es heute hier und da verschiedene Fresssituationen. Gut, f\u00fcr die Atlantischen Fleckendelfine (nur am Morgen) und auch die Gro\u00dfen [\u2026]","og_url":"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/","og_site_name":"Lobosonda | Whalewatching | Madeira","article_publisher":"https:\/\/www.facebook.com\/lobosonda\/","article_published_time":"2017-07-15T18:00:59+00:00","article_modified_time":"2017-07-07T14:55:47+00:00","og_image":[{"width":4252,"height":2835,"url":"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9808-2.jpg","type":"image\/jpeg"}],"author":"lobosonda","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"lobosonda","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/#article","isPartOf":{"@id":"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/"},"author":{"name":"lobosonda","@id":"https:\/\/blog.lobosonda.com\/de\/#\/schema\/person\/16135f75aca699492fd26a7141197b03"},"headline":"29.06.2017 \u2013 Fressen, fressen, fressen","datePublished":"2017-07-15T18:00:59+00:00","dateModified":"2017-07-07T14:55:47+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/"},"wordCount":156,"commentCount":0,"publisher":{"@id":"https:\/\/blog.lobosonda.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9808-2.jpg","articleSection":["Delfine","Fleckendelfin","Gemeiner Delfin","Gro\u00dfer T\u00fcmmler"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/","url":"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/","name":"29.06.2017 \u2013 Fressen, fressen, fressen - Lobosonda | Whalewatching | Madeira","isPartOf":{"@id":"https:\/\/blog.lobosonda.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/#primaryimage"},"image":{"@id":"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9808-2.jpg","datePublished":"2017-07-15T18:00:59+00:00","dateModified":"2017-07-07T14:55:47+00:00","breadcrumb":{"@id":"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/#primaryimage","url":"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9808-2.jpg","contentUrl":"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9808-2.jpg","width":4252,"height":2835},{"@type":"BreadcrumbList","@id":"https:\/\/blog.lobosonda.com\/de\/29-06-2017-fressen-fressen-fressen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.lobosonda.com\/de\/"},{"@type":"ListItem","position":2,"name":"29.06.2017 \u2013 Fressen, fressen, fressen"}]},{"@type":"WebSite","@id":"https:\/\/blog.lobosonda.com\/de\/#website","url":"https:\/\/blog.lobosonda.com\/de\/","name":"Lobosonda | Whalewatching | Madeira","description":"We stand for Water, Whales, Whale Watching, Whale conservation, Wellness and for Welcome. Lobosonda is a whale watching company respectful of all marine biodiversity operating in Madeira since 2003.","publisher":{"@id":"https:\/\/blog.lobosonda.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.lobosonda.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.lobosonda.com\/de\/#organization","name":"LobosOnda.com","url":"https:\/\/blog.lobosonda.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.lobosonda.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.lobosonda.com\/wp-content\/uploads\/2015\/04\/26167722_1853708551347437_4239983716863157418_n.jpg","contentUrl":"https:\/\/www.lobosonda.com\/wp-content\/uploads\/2015\/04\/26167722_1853708551347437_4239983716863157418_n.jpg","width":480,"height":480,"caption":"LobosOnda.com"},"image":{"@id":"https:\/\/blog.lobosonda.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lobosonda\/","https:\/\/instagram.com\/lobosonda\/","https:\/\/www.youtube.com\/user\/lobosonda"]},{"@type":"Person","@id":"https:\/\/blog.lobosonda.com\/de\/#\/schema\/person\/16135f75aca699492fd26a7141197b03","name":"lobosonda","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.lobosonda.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f333a6edc75221163a5147e29206c9fe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f333a6edc75221163a5147e29206c9fe?s=96&d=mm&r=g","caption":"lobosonda"},"url":"https:\/\/blog.lobosonda.com\/de\/author\/lobosonda\/"}]}},"jetpack_featured_media_url":"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/07\/DSC_9808-2.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/posts\/40312"}],"collection":[{"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/comments?post=40312"}],"version-history":[{"count":0,"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/posts\/40312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/media\/40309"}],"wp:attachment":[{"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/media?parent=40312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/categories?post=40312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/tags?post=40312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}