{"id":39042,"date":"2017-05-10T19:00:16","date_gmt":"2017-05-10T18:00:16","guid":{"rendered":"http:\/\/www.lobosonda.com\/?p=39042\/"},"modified":"2017-05-09T00:33:56","modified_gmt":"2017-05-08T23:33:56","slug":"02-05-2017-schlag-auf-schlag","status":"publish","type":"post","link":"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/","title":{"rendered":"02.05.2017 \u2013 Schlag auf Schlag"},"content":{"rendered":"<p style=\"text-align: justify;\">So kann es drau\u00dfen auf dem Meer zugehen, Schlag auf Schlag ging es heute auf der Stenella mit unseren 5 Delfinsichtungen. Freudig \u00fcberraschend war die erste Sichtung von Atlantischen Fleckendelfinen, die nun die Sommersaison einleuten. Gefolgt von unseren Winterdelfinen, den Gew\u00f6hnlichen Delfinen, die teils mit den eher scheuen Streifendelfinen gemeinsam auftraten. Dannach sahen wir ein Gr\u00fcppchen von Gro\u00dfen T\u00fcmmlern weit im Westen und wieder gen Osten beschlossen wir unsere Tour mit der Sichtung von Pilotwalen. Eine ganze Hand voll kamen die Sichtungen Schlag auf Schlag, ich bin noch ganz erschlagen \ud83d\ude09<\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: 10pt;\"><em>von Claudia Gomes<\/em><\/span><\/p>\n<p><span style=\"text-decoration: underline;\"><em><strong>Sichtungen des Tages<\/strong><\/em><\/span>:<\/p>\n<p>Ribeira Brava<\/p>\n<p><strong>10.00<\/strong>: Gew\u00f6hnliche Delfine, Pilotwale<\/p>\n<p><strong>14.30<\/strong>: Pilotwale, T\u00fcmmler<\/p>\n<p>Stenella<\/p>\n<p><strong>10.00<\/strong>: Fleckendelfine, Gew\u00f6hnliche Delfine, Streifendelfine, T\u00fcmmler, Pilotwale<\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#sc_gallery-1565 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#sc_gallery-1565 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 33.33%;\n\t\t\t\t}\n\t\t\t\t#sc_gallery-1565 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#sc_gallery-1565 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see sc_gallery() in functions\/theme-shortcodes.php *\/\n\t\t\t<\/style>\n\t\t<div id='sc_gallery-1565' class='gallery element_classes galleryid-39042 gallery-columns-3 gallery-size-thumbnail '><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/02-05-2017-schlag-auf-schlag\/dsc_4622-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4622-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4622-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4622-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4622-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4622-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/02-05-2017-schlag-auf-schlag\/dsc_4628-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4628-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4628-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4628-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4628-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4628-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/02-05-2017-schlag-auf-schlag\/dsc_4631-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4631-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4631-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4631-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4631-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4631-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/02-05-2017-schlag-auf-schlag\/dsc_4674\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4674-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4674-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4674-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4674-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4674-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/02-05-2017-schlag-auf-schlag\/dsc_4697-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4697-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4697-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4697-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4697-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4697-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/02-05-2017-schlag-auf-schlag\/dsc_5960-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_5960-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_5960-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_5960-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_5960-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_5960-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/02-05-2017-schlag-auf-schlag\/dsc_5969-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_5969-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_5969-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_5969-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_5969-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_5969-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/02-05-2017-schlag-auf-schlag\/dsc_5983\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_5983-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_5983-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_5983-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_5983-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_5983-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/02-05-2017-schlag-auf-schlag\/dsc_6013\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_6013-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_6013-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_6013-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_6013-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_6013-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/blog.lobosonda.com\/02-05-2017-schlag-auf-schlag\/dsc_6030-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_6030-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_6030-150x150.jpg 150w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_6030-500x500.jpg 500w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_6030-400x400.jpg 400w, https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_6030-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl>\n\t\t\t\t<br style='clear: both' \/>\n\t\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>So kann es drau\u00dfen auf dem Meer zugehen, Schlag auf Schlag ging es heute auf der Stenella mit unseren 5 Delfinsichtungen. Freudig \u00fcberraschend war die erste<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":4,"featured_media":39048,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_jetpack_memberships_contains_paid_content":false,"jetpack_publicize_message":"02.05.2017 \u2013 Schlag auf Schlag","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2},"_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[1837,1846,1844,1842,1839,1845],"tags":[],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>02.05.2017 \u2013 Schlag auf Schlag - Lobosonda | Whalewatching | Madeira<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"02.05.2017 \u2013 Schlag auf Schlag - Lobosonda | Whalewatching | Madeira\" \/>\n<meta property=\"og:description\" content=\"So kann es drau\u00dfen auf dem Meer zugehen, Schlag auf Schlag ging es heute auf der Stenella mit unseren 5 Delfinsichtungen. Freudig \u00fcberraschend war die erste [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/\" \/>\n<meta property=\"og:site_name\" content=\"Lobosonda | Whalewatching | Madeira\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lobosonda\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-10T18:00:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-08T23:33:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4631.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"5568\" \/>\n\t<meta property=\"og:image:height\" content=\"3712\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"lobosonda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"lobosonda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/\"},\"author\":{\"name\":\"lobosonda\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#\/schema\/person\/16135f75aca699492fd26a7141197b03\"},\"headline\":\"02.05.2017 \u2013 Schlag auf Schlag\",\"datePublished\":\"2017-05-10T18:00:16+00:00\",\"dateModified\":\"2017-05-08T23:33:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/\"},\"wordCount\":125,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4631.jpg\",\"articleSection\":[\"Delfine\",\"Fleckendelfin\",\"Gemeiner Delfin\",\"Gro\u00dfer T\u00fcmmler\",\"Pilotwal\",\"Streifendelfin\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/\",\"url\":\"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/\",\"name\":\"02.05.2017 \u2013 Schlag auf Schlag - Lobosonda | Whalewatching | Madeira\",\"isPartOf\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4631.jpg\",\"datePublished\":\"2017-05-10T18:00:16+00:00\",\"dateModified\":\"2017-05-08T23:33:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/#primaryimage\",\"url\":\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4631.jpg\",\"contentUrl\":\"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4631.jpg\",\"width\":5568,\"height\":3712},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.lobosonda.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"02.05.2017 \u2013 Schlag auf Schlag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#website\",\"url\":\"https:\/\/blog.lobosonda.com\/de\/\",\"name\":\"Lobosonda | Whalewatching | Madeira\",\"description\":\"We stand for Water, Whales, Whale Watching, Whale conservation, Wellness and for Welcome. Lobosonda is a whale watching company respectful of all marine biodiversity operating in Madeira since 2003.\",\"publisher\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.lobosonda.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#organization\",\"name\":\"LobosOnda.com\",\"url\":\"https:\/\/blog.lobosonda.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lobosonda.com\/wp-content\/uploads\/2015\/04\/26167722_1853708551347437_4239983716863157418_n.jpg\",\"contentUrl\":\"https:\/\/www.lobosonda.com\/wp-content\/uploads\/2015\/04\/26167722_1853708551347437_4239983716863157418_n.jpg\",\"width\":480,\"height\":480,\"caption\":\"LobosOnda.com\"},\"image\":{\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/lobosonda\/\",\"https:\/\/instagram.com\/lobosonda\/\",\"https:\/\/www.youtube.com\/user\/lobosonda\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#\/schema\/person\/16135f75aca699492fd26a7141197b03\",\"name\":\"lobosonda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/blog.lobosonda.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f333a6edc75221163a5147e29206c9fe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f333a6edc75221163a5147e29206c9fe?s=96&d=mm&r=g\",\"caption\":\"lobosonda\"},\"url\":\"https:\/\/blog.lobosonda.com\/de\/author\/lobosonda\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"02.05.2017 \u2013 Schlag auf Schlag - Lobosonda | Whalewatching | Madeira","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/","og_locale":"de_DE","og_type":"article","og_title":"02.05.2017 \u2013 Schlag auf Schlag - Lobosonda | Whalewatching | Madeira","og_description":"So kann es drau\u00dfen auf dem Meer zugehen, Schlag auf Schlag ging es heute auf der Stenella mit unseren 5 Delfinsichtungen. Freudig \u00fcberraschend war die erste [\u2026]","og_url":"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/","og_site_name":"Lobosonda | Whalewatching | Madeira","article_publisher":"https:\/\/www.facebook.com\/lobosonda\/","article_published_time":"2017-05-10T18:00:16+00:00","article_modified_time":"2017-05-08T23:33:56+00:00","og_image":[{"width":5568,"height":3712,"url":"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4631.jpg","type":"image\/jpeg"}],"author":"lobosonda","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"lobosonda","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/#article","isPartOf":{"@id":"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/"},"author":{"name":"lobosonda","@id":"https:\/\/blog.lobosonda.com\/de\/#\/schema\/person\/16135f75aca699492fd26a7141197b03"},"headline":"02.05.2017 \u2013 Schlag auf Schlag","datePublished":"2017-05-10T18:00:16+00:00","dateModified":"2017-05-08T23:33:56+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/"},"wordCount":125,"commentCount":0,"publisher":{"@id":"https:\/\/blog.lobosonda.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4631.jpg","articleSection":["Delfine","Fleckendelfin","Gemeiner Delfin","Gro\u00dfer T\u00fcmmler","Pilotwal","Streifendelfin"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/","url":"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/","name":"02.05.2017 \u2013 Schlag auf Schlag - Lobosonda | Whalewatching | Madeira","isPartOf":{"@id":"https:\/\/blog.lobosonda.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/#primaryimage"},"image":{"@id":"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4631.jpg","datePublished":"2017-05-10T18:00:16+00:00","dateModified":"2017-05-08T23:33:56+00:00","breadcrumb":{"@id":"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/#primaryimage","url":"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4631.jpg","contentUrl":"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4631.jpg","width":5568,"height":3712},{"@type":"BreadcrumbList","@id":"https:\/\/blog.lobosonda.com\/de\/02-05-2017-schlag-auf-schlag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.lobosonda.com\/de\/"},{"@type":"ListItem","position":2,"name":"02.05.2017 \u2013 Schlag auf Schlag"}]},{"@type":"WebSite","@id":"https:\/\/blog.lobosonda.com\/de\/#website","url":"https:\/\/blog.lobosonda.com\/de\/","name":"Lobosonda | Whalewatching | Madeira","description":"We stand for Water, Whales, Whale Watching, Whale conservation, Wellness and for Welcome. Lobosonda is a whale watching company respectful of all marine biodiversity operating in Madeira since 2003.","publisher":{"@id":"https:\/\/blog.lobosonda.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.lobosonda.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.lobosonda.com\/de\/#organization","name":"LobosOnda.com","url":"https:\/\/blog.lobosonda.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.lobosonda.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.lobosonda.com\/wp-content\/uploads\/2015\/04\/26167722_1853708551347437_4239983716863157418_n.jpg","contentUrl":"https:\/\/www.lobosonda.com\/wp-content\/uploads\/2015\/04\/26167722_1853708551347437_4239983716863157418_n.jpg","width":480,"height":480,"caption":"LobosOnda.com"},"image":{"@id":"https:\/\/blog.lobosonda.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lobosonda\/","https:\/\/instagram.com\/lobosonda\/","https:\/\/www.youtube.com\/user\/lobosonda"]},{"@type":"Person","@id":"https:\/\/blog.lobosonda.com\/de\/#\/schema\/person\/16135f75aca699492fd26a7141197b03","name":"lobosonda","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.lobosonda.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f333a6edc75221163a5147e29206c9fe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f333a6edc75221163a5147e29206c9fe?s=96&d=mm&r=g","caption":"lobosonda"},"url":"https:\/\/blog.lobosonda.com\/de\/author\/lobosonda\/"}]}},"jetpack_featured_media_url":"https:\/\/blog.lobosonda.com\/wp-content\/uploads\/2017\/05\/DSC_4631.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/posts\/39042"}],"collection":[{"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/comments?post=39042"}],"version-history":[{"count":0,"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/posts\/39042\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/media\/39048"}],"wp:attachment":[{"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/media?parent=39042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/categories?post=39042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.lobosonda.com\/de\/wp-json\/wp\/v2\/tags?post=39042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}